{"id":5443,"date":"2024-05-27T20:43:47","date_gmt":"2024-05-27T19:43:47","guid":{"rendered":"https:\/\/www.schirrmi.de\/blog\/?p=5443"},"modified":"2025-01-18T21:40:35","modified_gmt":"2025-01-18T20:40:35","slug":"oben-wird-gefressen-unten-wird-gelitten","status":"publish","type":"post","link":"https:\/\/www.schirrmi.de\/blog\/oben-wird-gefressen-unten-wird-gelitten\/","title":{"rendered":"Oben wird gefressen, unten wird gelitten"},"content":{"rendered":"<p>Staatsbankett in Bellevue, Mai 2024<\/p>\n<p>Der Sandkasten-Napoleon und Oma-Ficker besucht den nicht B\u00fcrgergew\u00e4hlten Gr\u00fc\u00dfaugust der BRD mitsamt Konsorten. Fr\u00f6hlichkeit, Koks und Steuergelder im \u00dcberma\u00df vorhanden.<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Macron-Steinmeier-am-Lachen.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5444\" src=\"https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Macron-Steinmeier-am-Lachen.jpg?resize=300%2C200&#038;ssl=1\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Macron-Steinmeier-am-Lachen.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Macron-Steinmeier-am-Lachen.jpg?resize=1024%2C681&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Macron-Steinmeier-am-Lachen.jpg?resize=768%2C511&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Macron-Steinmeier-am-Lachen.jpg?resize=1536%2C1022&amp;ssl=1 1536w, https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Macron-Steinmeier-am-Lachen.jpg?w=1623&amp;ssl=1 1623w, https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Macron-Steinmeier-am-Lachen.jpg?w=1208&amp;ssl=1 1208w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Macron: &#8222;Habt ihr eure B\u00fcrger, die Demokratie auch zusammenkn\u00fcppeln lassen?&#8220; Steinmeier (Guantanamo-Verbrecher) und Ehefrau (wenn ich nicht nach Fisch stinke, wer sonst?): &#8222;Haha, hihi &#8211; was denkst Du denn, mein kleiner Franzmann? BTW, wenn Du was lutschen willst, ich stehe zur Verf\u00fcgung. Harhar!!&#8220;<\/p>\n<p><a href=\"https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Scholz-im-Stuhl.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-5445\" src=\"https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Scholz-im-Stuhl.jpg?resize=269%2C300&#038;ssl=1\" alt=\"\" width=\"269\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Scholz-im-Stuhl.jpg?resize=269%2C300&amp;ssl=1 269w, https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Scholz-im-Stuhl.jpg?resize=919%2C1024&amp;ssl=1 919w, https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Scholz-im-Stuhl.jpg?resize=768%2C856&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.schirrmi.de\/blog\/wp-content\/uploads\/2024\/05\/Scholz-im-Stuhl.jpg?w=969&amp;ssl=1 969w\" sizes=\"auto, (max-width: 269px) 100vw, 269px\" \/><\/a><\/p>\n<p>Der Kriegstreiber und Antidemokrat sitzt zwar mit am Tisch, hat aber eher eine dienende Rolle. Tischclown mit Glatze. Hier im Bild: &#8222;Menno, h\u00f6rt doch mal auf mir auf die Glatze zu hauen! Wer war das?&#8220;<\/p>\n<p>Bon Appetit!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Staatsbankett in Bellevue, Mai 2024 Der Sandkasten-Napoleon und Oma-Ficker besucht den nicht B\u00fcrgergew\u00e4hlten Gr\u00fc\u00dfaugust der BRD mitsamt Konsorten. Fr\u00f6hlichkeit, Koks und Steuergelder im \u00dcberma\u00df vorhanden. Macron: &#8222;Habt ihr eure B\u00fcrger, die Demokratie auch zusammenkn\u00fcppeln lassen?&#8220; Steinmeier (Guantanamo-Verbrecher) und Ehefrau (wenn ich nicht nach Fisch stinke, wer sonst?): &#8222;Haha, hihi &#8211; was denkst Du denn, mein &hellip; <a href=\"https:\/\/www.schirrmi.de\/blog\/oben-wird-gefressen-unten-wird-gelitten\/\" class=\"more-link\"><span class=\"screen-reader-text\">Oben wird gefressen, unten wird gelitten<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[517,1159,1160,834,1161,1162],"class_list":["post-5443","post","type-post","status-publish","format-standard","hentry","category-blog","tag-arschloecher","tag-gruessaugust","tag-kanzler","tag-kriegstreiber","tag-schwanzlutscher","tag-steuerzahler"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3l7Rv-1pN","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/posts\/5443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/comments?post=5443"}],"version-history":[{"count":1,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/posts\/5443\/revisions"}],"predecessor-version":[{"id":5446,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/posts\/5443\/revisions\/5446"}],"wp:attachment":[{"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/media?parent=5443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/categories?post=5443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/tags?post=5443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}