{"id":4310,"date":"2017-02-04T18:14:38","date_gmt":"2017-02-04T17:14:38","guid":{"rendered":"https:\/\/www.schirrmi.de\/blog\/?p=4310"},"modified":"2025-01-18T21:40:42","modified_gmt":"2025-01-18T20:40:42","slug":"der-multiple-haircut","status":"publish","type":"post","link":"https:\/\/www.schirrmi.de\/blog\/der-multiple-haircut\/","title":{"rendered":"Der multiple Haircut"},"content":{"rendered":"<p>Komisch irgendwie. Wenn man mal anf\u00e4ngt, h\u00f6rt es nicht auf.<\/p>\n<p>Innerhalb von 45 Minuten Mittagspause fuhr ich in das Industriegebiet, parkte recht schnell und joggte in das Establishment, nicht ohne vorher mit breiten Schultern und strengem Blick ein paar anderen Kunden den Vortritt \u2013 nicht zu lassen.<\/p>\n<p>So k\u00fcrzte man mir die Matte in einer atemberaubenden Zeit, es sprang ein Heiermann f\u00fcr die Dame heraus. Die Zeit reichte noch um in den anderen Ort zu fahren, kurz zu Mittag zu fressen, danach noch schei\u00dfen, H\u00e4nde waschen, Z\u00e4hne putzen und wieder, p\u00fcnktlich in der Knochenm\u00fchle zu sein.<\/p>\n<p>Die \u00fcberaus nette und vollkommen t\u00e4towierte Dame k\u00fcrzte zun\u00e4chst mein Haupthaar (\u201ebitte oben nicht allzu kurz, da ist es n\u00e4mlich ein wenig sch\u00fctter\u201c) und befragte meine Augenbrauen. Ich bejahte. B\u00fcro: W\u00e4hrend ich mich \u00fcber ein Problem gr\u00fcbelnd im Gesicht streichelte, fielen mir \u00fcberaus n\u00fctzliche aber wenig attraktive Dr\u00e4hte auf. In der Nase. Nahm dann den uralten Rasierer, in stillem Gedenken an die liebe Evi \u2013 von ihr erhielt ich ihn Annodazumal, und k\u00fcrzte kleine Nasenlochborsten.<\/p>\n<p>Jetzt r\u00fcckblickend bin ich froh und stolz das an der Haarfront Tabularasa gemacht wurde. Trotzdem bin ich noch nicht zufrieden, stelle ich grade fest als ich vom pinkeln kam. Ich schaute n\u00e4mlich runter..<\/p>\n<p>Mit intimen Gr\u00fc\u00dfen..<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Komisch irgendwie. Wenn man mal anf\u00e4ngt, h\u00f6rt es nicht auf. Innerhalb von 45 Minuten Mittagspause fuhr ich in das Industriegebiet, parkte recht schnell und joggte in das Establishment, nicht ohne vorher mit breiten Schultern und strengem Blick ein paar anderen Kunden den Vortritt \u2013 nicht zu lassen. So k\u00fcrzte man mir die Matte in einer &hellip; <a href=\"https:\/\/www.schirrmi.de\/blog\/der-multiple-haircut\/\" class=\"more-link\"><span class=\"screen-reader-text\">Der multiple Haircut<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[18],"class_list":["post-4310","post","type-post","status-publish","format-standard","hentry","category-blog","tag-alltag"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p3l7Rv-17w","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/posts\/4310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/comments?post=4310"}],"version-history":[{"count":1,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/posts\/4310\/revisions"}],"predecessor-version":[{"id":4311,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/posts\/4310\/revisions\/4311"}],"wp:attachment":[{"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/media?parent=4310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/categories?post=4310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schirrmi.de\/blog\/wp-json\/wp\/v2\/tags?post=4310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}